{"id":67636,"date":"2025-10-13T17:00:41","date_gmt":"2025-10-13T20:00:41","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=67636"},"modified":"2025-10-13T10:53:47","modified_gmt":"2025-10-13T13:53:47","slug":"arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/","title":{"rendered":"Arquiteto e Urbanista &#8211; Exclusiva para PPQ &#8211; Cadastro Reserva &#8211; CASAI &#8211; S\u00e3o Paulo &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>As regras que orientam sua candidatura, assim como os prazos estabelecidos, est\u00e3o detalhadas nos documentos abaixo.<\/li>\n<li>\u00c9 fundamental que voc\u00ea leia atentamente todas as informa\u00e7\u00f5es antes de finalizar sua inscri\u00e7\u00e3o.<\/li>\n<li>EDITAL 53 CASAI NACIONAL SAO PAULO<\/li>\n<li>CRONOGRAMA EDITAL 53<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos obrigat\u00f3rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Superior; Diploma de forma\u00e7\u00e3o superior em Arquitetura e Urbanismo emitido por institui\u00e7\u00e3o superior de educa\u00e7\u00e3o reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o;<\/li>\n<li>Registro no Conselho Regional de Arquitetura e Urbanismo do estado de atua\u00e7\u00e3o.<\/li>\n<li>Disponibilidade para viagens a\u00e9reas, terrestres ou fluviais.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades e Responsabilidades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Elaborar projetos arquitet\u00f4nicos para estabelecimentos de sa\u00fade e administrativos, seguindo a legisla\u00e7\u00e3o vigente, criar manuais e normas, fiscalizar obras, propor solu\u00e7\u00f5es para conforto t\u00e9rmico, luminoso e acessibilidade, auxiliar em reformas e amplia\u00e7\u00f5es, e gerenciar res\u00edduos s\u00f3lidos em aldeias ind\u00edgenas.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>40 horas semanais<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Remunera\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 12.903,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Alimenta\u00e7\u00e3o<\/li>\n<li>Vale Refei\u00e7\u00e3o<\/li>\n<li>Vale Transporte<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">N\u00edvel: Profissional<\/p>\n<p style=\"text-align: justify;\">Regime de contrata\u00e7\u00e3o: Efetivo \u2013 CLT<\/p>\n<p style=\"text-align: justify;\">Cadastrar curr\u00edculo informando no assunto a vaga de interesse para o Link<br \/>\nhttps:\/\/www.empregare.com\/pt-br\/vaga-arquiteto-e-urbanista-exclusiva-para-ppq_133448<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descri\u00e7\u00e3o: As regras que orientam sua candidatura, assim como os prazos estabelecidos, est\u00e3o detalhadas nos documentos abaixo. \u00c9 fundamental que voc\u00ea leia atentamente todas as [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,117],"tags":[],"class_list":["post-67636","post","type-post","status-publish","format-standard","hentry","category-arquiteto-decorador-designer","category-ensino-superior"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Descri\u00e7\u00e3o: As regras que orientam sua candidatura, assim como os prazos estabelecidos, est\u00e3o detalhadas nos documentos abaixo. \u00c9 fundamental que voc\u00ea leia atentamente todas as [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T20:00:41+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Arquiteto e Urbanista &#8211; Exclusiva para PPQ &#8211; Cadastro Reserva &#8211; CASAI &#8211; S\u00e3o Paulo &#8211; SP\",\"datePublished\":\"2025-10-13T20:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"arquitetura e decora\u00e7\u00e3o\",\"ensino superior\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/\",\"name\":\"Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-10-13T20:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/10\\\/13\\\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquiteto e Urbanista &#8211; Exclusiva para PPQ &#8211; Cadastro Reserva &#8211; CASAI &#8211; S\u00e3o Paulo &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP","og_description":"Descri\u00e7\u00e3o: As regras que orientam sua candidatura, assim como os prazos estabelecidos, est\u00e3o detalhadas nos documentos abaixo. \u00c9 fundamental que voc\u00ea leia atentamente todas as [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-10-13T20:00:41+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Arquiteto e Urbanista &#8211; Exclusiva para PPQ &#8211; Cadastro Reserva &#8211; CASAI &#8211; S\u00e3o Paulo &#8211; SP","datePublished":"2025-10-13T20:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/"},"wordCount":206,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["arquitetura e decora\u00e7\u00e3o","ensino superior"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/","name":"Arquiteto e Urbanista - Exclusiva para PPQ - Cadastro Reserva - CASAI - S\u00e3o Paulo - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-10-13T20:00:41+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/10\/13\/arquiteto-e-urbanista-exclusiva-para-ppq-cadastro-reserva-casai-sao-paulo-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Arquiteto e Urbanista &#8211; Exclusiva para PPQ &#8211; Cadastro Reserva &#8211; CASAI &#8211; S\u00e3o Paulo &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67636"}],"version-history":[{"count":2,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67636\/revisions"}],"predecessor-version":[{"id":67638,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67636\/revisions\/67638"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}