{"id":67477,"date":"2025-09-23T10:00:07","date_gmt":"2025-09-23T13:00:07","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=67477"},"modified":"2025-09-23T09:37:38","modified_gmt":"2025-09-23T12:37:38","slug":"auxiliar-de-producao-diadema-sp-3","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/","title":{"rendered":"Auxiliar de Produ\u00e7\u00e3o &#8211;  Diadema \/ SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Atribui\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Empresa: G Safety<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Fundamental Completo<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Pesar chapas, limpar moinho, analisar validade de produtos, usar bobinas com etiqueta e analisar a qualidade das mercadorias<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Escala 6\u00d72 das 14:00 \u00e0s 22:00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.242,62<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Refei\u00e7\u00e3o no Local<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:selecao1@gsafety.com.br\">selecao1@gsafety.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atribui\u00e7\u00f5es: Empresa: G Safety Requisitos: Ensino Fundamental Completo Atividades: Pesar chapas, limpar moinho, analisar validade de produtos, usar bobinas com etiqueta e analisar a qualidade [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113,48],"tags":[],"class_list":["post-67477","post","type-post","status-publish","format-standard","hentry","category-ensino-fundamental","category-auxiliar-producao-industria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auxiliar de Produ\u00e7\u00e3o - Diadema \/ SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auxiliar de Produ\u00e7\u00e3o - Diadema \/ SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Atribui\u00e7\u00f5es: Empresa: G Safety Requisitos: Ensino Fundamental Completo Atividades: Pesar chapas, limpar moinho, analisar validade de produtos, usar bobinas com etiqueta e analisar a qualidade [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T13:00:07+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Auxiliar de Produ\u00e7\u00e3o &#8211; Diadema \\\/ SP\",\"datePublished\":\"2025-09-23T13:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"ensino fundamental\",\"ind\u00fastria\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/\",\"name\":\"Auxiliar de Produ\u00e7\u00e3o - Diadema \\\/ SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-09-23T13:00:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/09\\\/23\\\/auxiliar-de-producao-diadema-sp-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auxiliar de Produ\u00e7\u00e3o &#8211; Diadema \\\/ SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auxiliar de Produ\u00e7\u00e3o - Diadema \/ SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Auxiliar de Produ\u00e7\u00e3o - Diadema \/ SP - VagasEmpregoSP","og_description":"Atribui\u00e7\u00f5es: Empresa: G Safety Requisitos: Ensino Fundamental Completo Atividades: Pesar chapas, limpar moinho, analisar validade de produtos, usar bobinas com etiqueta e analisar a qualidade [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-09-23T13:00:07+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Auxiliar de Produ\u00e7\u00e3o &#8211; Diadema \/ SP","datePublished":"2025-09-23T13:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/"},"wordCount":69,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["ensino fundamental","ind\u00fastria"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/","name":"Auxiliar de Produ\u00e7\u00e3o - Diadema \/ SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-09-23T13:00:07+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/09\/23\/auxiliar-de-producao-diadema-sp-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Auxiliar de Produ\u00e7\u00e3o &#8211; Diadema \/ SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67477"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67477\/revisions"}],"predecessor-version":[{"id":67478,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67477\/revisions\/67478"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}