{"id":66582,"date":"2025-07-10T13:00:50","date_gmt":"2025-07-10T16:00:50","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=66582"},"modified":"2025-07-09T21:38:45","modified_gmt":"2025-07-10T00:38:45","slug":"analista-fiscal-campinas-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/","title":{"rendered":"Analista Fiscal &#8211; Campinas &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino Superior Completo ou Cursando Ci\u00eancias Cont\u00e1beis, Administra\u00e7\u00e3o, Economia;<\/li>\n<li>Conhecimento em escritura\u00e7\u00e3o Fiscal em Geral (Notas Fiscais de Entradas e Sa\u00eddas);<\/li>\n<li>Conhecimento t\u00e9cnico nos impostos indiretos, sendo: IPI, ICMS, ISS, PIS e COFINS, assim como tamb\u00e9m a elabora\u00e7\u00e3o das suas respectivas apura\u00e7\u00f5es;<\/li>\n<li>Conhecimento t\u00e9cnico nas Reten\u00e7\u00f5es na Fonte de INSS, IRRF e CSRF (PIS, COFINS e CSLL);<\/li>\n<li>Conhecimento no sistema Giss Online , Rodopar, Dom\u00ednio e Totvs.<\/li>\n<li>Conhecimento t\u00e9cnico nas obriga\u00e7\u00f5es acess\u00f3rias Estaduais e Federais<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades e Responsabilidades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Realizar apura\u00e7\u00e3o e confer\u00eancia de impostos diretos e indiretos (ICMS, IPI, PIS, COFINS, ISS, IRPJ, CSLL); Efetuar lan\u00e7amentos e escritura\u00e7\u00e3o fiscal de notas fiscais de entrada, sa\u00edda, servi\u00e7os e importa\u00e7\u00e3o; Elaborar e transmitir obriga\u00e7\u00f5es acess\u00f3rias (SPED Fiscal, SPED Contribui\u00e7\u00f5es, DCTF, GIA, EFD-Reinf, DIRF, etc.);<\/li>\n<li>Classificar e conferir documentos fiscais conforme legisla\u00e7\u00e3o vigente;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Hor\u00e1rio das 08:00 \u00e1s 17:00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Remunera\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 3.500,00 at\u00e9 R$ 4.000,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Assist\u00eancia odontol\u00f3gica<\/li>\n<li>Seguro de Vida<\/li>\n<li>Vale refei\u00e7\u00e3o<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Cadastrar curr\u00edculo informando no assunto a vaga de interesse para o Link<br \/>\nhttps:\/\/www.empregare.com\/pt-br\/vaga-analista-fiscal_121114<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino Superior Completo ou Cursando Ci\u00eancias Cont\u00e1beis, Administra\u00e7\u00e3o, Economia; Conhecimento em escritura\u00e7\u00e3o Fiscal em Geral (Notas Fiscais de Entradas e Sa\u00eddas); Conhecimento t\u00e9cnico nos [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,18,117,118],"tags":[],"class_list":["post-66582","post","type-post","status-publish","format-standard","hentry","category-administrativa","category-contabil-financeiro-contabilista-contador-tecnico","category-ensino-superior","category-ensino-superior-incompleto-em-andamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analista Fiscal - Campinas - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analista Fiscal - Campinas - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino Superior Completo ou Cursando Ci\u00eancias Cont\u00e1beis, Administra\u00e7\u00e3o, Economia; Conhecimento em escritura\u00e7\u00e3o Fiscal em Geral (Notas Fiscais de Entradas e Sa\u00eddas); Conhecimento t\u00e9cnico nos [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T16:00:50+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Analista Fiscal &#8211; Campinas &#8211; SP\",\"datePublished\":\"2025-07-10T16:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/\"},\"wordCount\":205,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"administra\u00e7\u00e3o geral\",\"cont\u00e1bil \\\/ financeiro\",\"ensino superior\",\"ensino superior incompleto\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/\",\"name\":\"Analista Fiscal - Campinas - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-07-10T16:00:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/10\\\/analista-fiscal-campinas-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analista Fiscal &#8211; Campinas &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analista Fiscal - Campinas - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Analista Fiscal - Campinas - SP - VagasEmpregoSP","og_description":"Requisitos: Ensino Superior Completo ou Cursando Ci\u00eancias Cont\u00e1beis, Administra\u00e7\u00e3o, Economia; Conhecimento em escritura\u00e7\u00e3o Fiscal em Geral (Notas Fiscais de Entradas e Sa\u00eddas); Conhecimento t\u00e9cnico nos [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-07-10T16:00:50+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Analista Fiscal &#8211; Campinas &#8211; SP","datePublished":"2025-07-10T16:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/"},"wordCount":205,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["administra\u00e7\u00e3o geral","cont\u00e1bil \/ financeiro","ensino superior","ensino superior incompleto"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/","name":"Analista Fiscal - Campinas - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-07-10T16:00:50+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/10\/analista-fiscal-campinas-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Analista Fiscal &#8211; Campinas &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=66582"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66582\/revisions"}],"predecessor-version":[{"id":66583,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66582\/revisions\/66583"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=66582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=66582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=66582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}