{"id":66563,"date":"2025-07-09T14:00:09","date_gmt":"2025-07-09T17:00:09","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=66563"},"modified":"2025-07-08T22:48:14","modified_gmt":"2025-07-09T01:48:14","slug":"porteiro-polvilho-cajamar-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/","title":{"rendered":"Porteiro &#8211; Polvilho \u2013 Cajamar &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Necess\u00e1rio morar perto de Cajamar<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Atender chamados de moradores, anotar encomendas recebidas, passar recados e olhar c\u00e2meras<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Disponibilidade de Hor\u00e1rio<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.021,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Vale Alimenta\u00e7\u00e3o R$ 144,68 + Conv\u00eanio Odontol\u00f3gico + Totalpass + Assiduidade R$ 300,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto da vaga de interesse pelo WhatsApp11 97550-6047<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Necess\u00e1rio morar perto de Cajamar Atividades: Atender chamados de moradores, anotar encomendas recebidas, passar recados e olhar c\u00e2meras Jornada de trabalho: Disponibilidade de Hor\u00e1rio [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-66563","post","type-post","status-publish","format-standard","hentry","category-seguranca-patrimonial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Necess\u00e1rio morar perto de Cajamar Atividades: Atender chamados de moradores, anotar encomendas recebidas, passar recados e olhar c\u00e2meras Jornada de trabalho: Disponibilidade de Hor\u00e1rio [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-09T17:00:09+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Porteiro &#8211; Polvilho \u2013 Cajamar &#8211; SP\",\"datePublished\":\"2025-07-09T17:00:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/\"},\"wordCount\":65,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"seguran\u00e7a patrimonial\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/\",\"name\":\"Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-07-09T17:00:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/porteiro-polvilho-cajamar-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porteiro &#8211; Polvilho \u2013 Cajamar &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP","og_description":"Requisitos: Necess\u00e1rio morar perto de Cajamar Atividades: Atender chamados de moradores, anotar encomendas recebidas, passar recados e olhar c\u00e2meras Jornada de trabalho: Disponibilidade de Hor\u00e1rio [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-07-09T17:00:09+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Porteiro &#8211; Polvilho \u2013 Cajamar &#8211; SP","datePublished":"2025-07-09T17:00:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/"},"wordCount":65,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["seguran\u00e7a patrimonial"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/","name":"Porteiro - Polvilho \u2013 Cajamar - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-07-09T17:00:09+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/09\/porteiro-polvilho-cajamar-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Porteiro &#8211; Polvilho \u2013 Cajamar &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=66563"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66563\/revisions"}],"predecessor-version":[{"id":66564,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66563\/revisions\/66564"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=66563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=66563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=66563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}