{"id":66496,"date":"2025-07-04T13:00:59","date_gmt":"2025-07-04T16:00:59","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=66496"},"modified":"2025-07-03T20:01:12","modified_gmt":"2025-07-03T23:01:12","slug":"operador-de-producao-guarulhos-zona-norte-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/","title":{"rendered":"Operador de Produ\u00e7\u00e3o &#8211;  Guarulhos \u2013 Zona Norte &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Empresa: WCA Brasil<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino fundamental completo<\/li>\n<li>Maior de 18 anos<\/li>\n<li>N\u00e3o precisa experi\u00eancia<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Preencher m\u00e1quinas com insumos necess\u00e1rio para inje\u00e7\u00e3o de produtos<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Disponibilidade de Hor\u00e1rio<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.000,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Cesta-B\u00e1sica + Refei\u00e7\u00e3o no Local + Ap\u00f3s Experi\u00eancia Bonifica\u00e7\u00e3o R$ 187,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Interessados devem comparecer dia 08\/07\/2025 \u00c0s 14:00 no CIC Ja\u00e7an\u00e3<br \/>\nEndere\u00e7o: Rua Ari da Rocha Miranda, 36 \u2013 Conj. Hab. Jova Rural \u2013 S\u00e3o Paulo \/ SP<br \/>\nLevar c\u00f3pia dos documentos e curr\u00edculo impresso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descri\u00e7\u00e3o: Empresa: WCA Brasil Requisitos: Ensino fundamental completo Maior de 18 anos N\u00e3o precisa experi\u00eancia Atividades: Preencher m\u00e1quinas com insumos necess\u00e1rio para inje\u00e7\u00e3o de produtos [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113,48,73],"tags":[],"class_list":["post-66496","post","type-post","status-publish","format-standard","hentry","category-ensino-fundamental","category-auxiliar-producao-industria","category-operacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Descri\u00e7\u00e3o: Empresa: WCA Brasil Requisitos: Ensino fundamental completo Maior de 18 anos N\u00e3o precisa experi\u00eancia Atividades: Preencher m\u00e1quinas com insumos necess\u00e1rio para inje\u00e7\u00e3o de produtos [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T16:00:59+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Operador de Produ\u00e7\u00e3o &#8211; Guarulhos \u2013 Zona Norte &#8211; SP\",\"datePublished\":\"2025-07-04T16:00:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/\"},\"wordCount\":100,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"ensino fundamental\",\"ind\u00fastria\",\"operacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/\",\"name\":\"Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-07-04T16:00:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/07\\\/04\\\/operador-de-producao-guarulhos-zona-norte-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Operador de Produ\u00e7\u00e3o &#8211; Guarulhos \u2013 Zona Norte &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP","og_description":"Descri\u00e7\u00e3o: Empresa: WCA Brasil Requisitos: Ensino fundamental completo Maior de 18 anos N\u00e3o precisa experi\u00eancia Atividades: Preencher m\u00e1quinas com insumos necess\u00e1rio para inje\u00e7\u00e3o de produtos [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-07-04T16:00:59+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Operador de Produ\u00e7\u00e3o &#8211; Guarulhos \u2013 Zona Norte &#8211; SP","datePublished":"2025-07-04T16:00:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/"},"wordCount":100,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["ensino fundamental","ind\u00fastria","operacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/","name":"Operador de Produ\u00e7\u00e3o - Guarulhos \u2013 Zona Norte - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-07-04T16:00:59+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/07\/04\/operador-de-producao-guarulhos-zona-norte-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Operador de Produ\u00e7\u00e3o &#8211; Guarulhos \u2013 Zona Norte &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=66496"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66496\/revisions"}],"predecessor-version":[{"id":66497,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66496\/revisions\/66497"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=66496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=66496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=66496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}