{"id":66393,"date":"2025-06-27T13:00:29","date_gmt":"2025-06-27T16:00:29","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=66393"},"modified":"2025-06-26T23:05:56","modified_gmt":"2025-06-27T02:05:56","slug":"assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/","title":{"rendered":"Assistente \/ Auxiliar de DP &#8211;  Home Office e Zona Sul \u2013 S\u00e3o Paulo &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Necess\u00e1rio forma\u00e7\u00e3o em Contabilidade, Administra\u00e7\u00e3o e Recursos Humanos<\/li>\n<li>Conhecimentos em Legisla\u00e7\u00e3o trabalhista<\/li>\n<li>Experi\u00eancia em sistema de dom\u00ednio<\/li>\n<li>Excel Intermedi\u00e1rio<\/li>\n<li>Boa comunica\u00e7\u00e3o verbal e escrita<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Rotina de admiss\u00e3o, emiss\u00e3o de folha de pagamento fechamento mensal e setor administrativo<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda \u00e0 Quinta Feira das 08:00 \u00e0s 18:00 e Sexta home office das 08:15 \u00e0s 17:30<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.000,00 \u00e0 R$ 2.900,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Vale-Refei\u00e7\u00e3o + Seguro Vida<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:anne@emis.com.br\">anne@emis.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Necess\u00e1rio forma\u00e7\u00e3o em Contabilidade, Administra\u00e7\u00e3o e Recursos Humanos Conhecimentos em Legisla\u00e7\u00e3o trabalhista Experi\u00eancia em sistema de dom\u00ednio Excel Intermedi\u00e1rio Boa comunica\u00e7\u00e3o verbal e escrita [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,18,117,86],"tags":[],"class_list":["post-66393","post","type-post","status-publish","format-standard","hentry","category-administrativa","category-contabil-financeiro-contabilista-contador-tecnico","category-ensino-superior","category-recursos-humanos-departamento-pessoal-rh-dp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assistente \/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistente \/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Necess\u00e1rio forma\u00e7\u00e3o em Contabilidade, Administra\u00e7\u00e3o e Recursos Humanos Conhecimentos em Legisla\u00e7\u00e3o trabalhista Experi\u00eancia em sistema de dom\u00ednio Excel Intermedi\u00e1rio Boa comunica\u00e7\u00e3o verbal e escrita [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T16:00:29+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Assistente \\\/ Auxiliar de DP &#8211; Home Office e Zona Sul \u2013 S\u00e3o Paulo &#8211; SP\",\"datePublished\":\"2025-06-27T16:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"administra\u00e7\u00e3o geral\",\"cont\u00e1bil \\\/ financeiro\",\"ensino superior\",\"RH \\\/ DP\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/\",\"name\":\"Assistente \\\/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-06-27T16:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/06\\\/27\\\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assistente \\\/ Auxiliar de DP &#8211; Home Office e Zona Sul \u2013 S\u00e3o Paulo &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistente \/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Assistente \/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP","og_description":"Requisitos: Necess\u00e1rio forma\u00e7\u00e3o em Contabilidade, Administra\u00e7\u00e3o e Recursos Humanos Conhecimentos em Legisla\u00e7\u00e3o trabalhista Experi\u00eancia em sistema de dom\u00ednio Excel Intermedi\u00e1rio Boa comunica\u00e7\u00e3o verbal e escrita [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-06-27T16:00:29+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Assistente \/ Auxiliar de DP &#8211; Home Office e Zona Sul \u2013 S\u00e3o Paulo &#8211; SP","datePublished":"2025-06-27T16:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/"},"wordCount":107,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["administra\u00e7\u00e3o geral","cont\u00e1bil \/ financeiro","ensino superior","RH \/ DP"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/","name":"Assistente \/ Auxiliar de DP - Home Office e Zona Sul \u2013 S\u00e3o Paulo - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-06-27T16:00:29+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/06\/27\/assistente-auxiliar-de-dp-home-office-e-zona-sul-sao-paulo-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Assistente \/ Auxiliar de DP &#8211; Home Office e Zona Sul \u2013 S\u00e3o Paulo &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=66393"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66393\/revisions"}],"predecessor-version":[{"id":66394,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/66393\/revisions\/66394"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=66393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=66393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=66393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}