{"id":65819,"date":"2025-05-21T09:00:39","date_gmt":"2025-05-21T12:00:39","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=65819"},"modified":"2025-05-21T09:00:39","modified_gmt":"2025-05-21T12:00:39","slug":"operador-de-caixa-de-loja-sao-paulo-sp-2","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/","title":{"rendered":"Operador de Caixa de Loja &#8211; S\u00e3o Paulo &#8211; SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Atribui\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Empresa: Casa da Arte<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Conhecimentos na \u00e1rea<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ficar no caixa atendendo e recebendo pagamentos via Pix e cart\u00e3o de cr\u00e9dito<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira das 09:30 \u00e0s 18:30 e S\u00e1bados das 09:15 \u00e0s 14:30<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.000,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Alimenta\u00e7\u00e3o no Local + Quebra de Caixa<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Localiza\u00e7\u00e3o: Santana \u2013 Zona Norte \/ SP<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto a vaga de interesse pelo fone WhatsApp 11 98961-7203<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atribui\u00e7\u00f5es: Empresa: Casa da Arte Requisitos: Conhecimentos na \u00e1rea Descri\u00e7\u00e3o: Ficar no caixa atendendo e recebendo pagamentos via Pix e cart\u00e3o de cr\u00e9dito Jornada de [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,73],"tags":[],"class_list":["post-65819","post","type-post","status-publish","format-standard","hentry","category-atendente-recepcionista-balconista","category-operacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Atribui\u00e7\u00f5es: Empresa: Casa da Arte Requisitos: Conhecimentos na \u00e1rea Descri\u00e7\u00e3o: Ficar no caixa atendendo e recebendo pagamentos via Pix e cart\u00e3o de cr\u00e9dito Jornada de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T12:00:39+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Operador de Caixa de Loja &#8211; S\u00e3o Paulo &#8211; SP\",\"datePublished\":\"2025-05-21T12:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/\"},\"wordCount\":86,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"atendimento e recep\u00e7\u00e3o\",\"operacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/\",\"name\":\"Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-05-21T12:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/05\\\/21\\\/operador-de-caixa-de-loja-sao-paulo-sp-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Operador de Caixa de Loja &#8211; S\u00e3o Paulo &#8211; SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP","og_description":"Atribui\u00e7\u00f5es: Empresa: Casa da Arte Requisitos: Conhecimentos na \u00e1rea Descri\u00e7\u00e3o: Ficar no caixa atendendo e recebendo pagamentos via Pix e cart\u00e3o de cr\u00e9dito Jornada de [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-05-21T12:00:39+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Operador de Caixa de Loja &#8211; S\u00e3o Paulo &#8211; SP","datePublished":"2025-05-21T12:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/"},"wordCount":86,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["atendimento e recep\u00e7\u00e3o","operacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/","name":"Operador de Caixa de Loja - S\u00e3o Paulo - SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-05-21T12:00:39+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/05\/21\/operador-de-caixa-de-loja-sao-paulo-sp-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Operador de Caixa de Loja &#8211; S\u00e3o Paulo &#8211; SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/65819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=65819"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/65819\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=65819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=65819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=65819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}