{"id":64321,"date":"2025-01-17T16:00:15","date_gmt":"2025-01-17T19:00:15","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=64321"},"modified":"2025-01-17T16:00:15","modified_gmt":"2025-01-17T19:00:15","slug":"auxiliar-de-logistica-osasco-zona-oeste-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/","title":{"rendered":"Auxiliar de Log\u00edstica &#8211; Osasco \u2013 Zona Oeste \/ SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Atribui\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Empresa: Dipack Log\u00edstica<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino fundamental completo<\/li>\n<li>N\u00e3o precisa de experi\u00eancia na \u00e1rea<\/li>\n<li>Viv\u00eancia com atividades de esfor\u00e7o f\u00edsico<\/li>\n<li>Disponibilidade de Hor\u00e1rio<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ser\u00e1 Mencionado no Ato da Entrevista<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Remunera\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Sal\u00e1rio Fixo<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Refei\u00e7\u00e3o no Local + Fretado<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:breno.santos@dipack.com.br\">breno.santos@dipack.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atribui\u00e7\u00f5es: Empresa: Dipack Log\u00edstica Requisitos: Ensino fundamental completo N\u00e3o precisa de experi\u00eancia na \u00e1rea Viv\u00eancia com atividades de esfor\u00e7o f\u00edsico Disponibilidade de Hor\u00e1rio Descri\u00e7\u00e3o: Ser\u00e1 [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[113,59],"tags":[],"class_list":["post-64321","post","type-post","status-publish","format-standard","hentry","category-ensino-fundamental","category-logistica-transportes-motorista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \/ SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \/ SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Atribui\u00e7\u00f5es: Empresa: Dipack Log\u00edstica Requisitos: Ensino fundamental completo N\u00e3o precisa de experi\u00eancia na \u00e1rea Viv\u00eancia com atividades de esfor\u00e7o f\u00edsico Disponibilidade de Hor\u00e1rio Descri\u00e7\u00e3o: Ser\u00e1 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T19:00:15+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Auxiliar de Log\u00edstica &#8211; Osasco \u2013 Zona Oeste \\\/ SP\",\"datePublished\":\"2025-01-17T19:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"ensino fundamental\",\"log\u00edstica \\\/ distribui\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/\",\"name\":\"Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \\\/ SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2025-01-17T19:00:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2025\\\/01\\\/17\\\/auxiliar-de-logistica-osasco-zona-oeste-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auxiliar de Log\u00edstica &#8211; Osasco \u2013 Zona Oeste \\\/ SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \/ SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \/ SP - VagasEmpregoSP","og_description":"Atribui\u00e7\u00f5es: Empresa: Dipack Log\u00edstica Requisitos: Ensino fundamental completo N\u00e3o precisa de experi\u00eancia na \u00e1rea Viv\u00eancia com atividades de esfor\u00e7o f\u00edsico Disponibilidade de Hor\u00e1rio Descri\u00e7\u00e3o: Ser\u00e1 [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2025-01-17T19:00:15+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Auxiliar de Log\u00edstica &#8211; Osasco \u2013 Zona Oeste \/ SP","datePublished":"2025-01-17T19:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/"},"wordCount":78,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["ensino fundamental","log\u00edstica \/ distribui\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/","name":"Auxiliar de Log\u00edstica - Osasco \u2013 Zona Oeste \/ SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2025-01-17T19:00:15+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2025\/01\/17\/auxiliar-de-logistica-osasco-zona-oeste-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Auxiliar de Log\u00edstica &#8211; Osasco \u2013 Zona Oeste \/ SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=64321"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64321\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=64321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=64321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=64321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}