{"id":63628,"date":"2024-08-19T09:00:25","date_gmt":"2024-08-19T12:00:25","guid":{"rendered":"https:\/\/www.vagasempregosp.com.br\/?p=63628"},"modified":"2024-08-19T09:00:25","modified_gmt":"2024-08-19T12:00:25","slug":"estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp","status":"publish","type":"post","link":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/","title":{"rendered":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia &#8211; S\u00e3o Paulo \u2013 SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Estar matriculado em curso de gradua\u00e7\u00e3o em Ci\u00eancia da Computa\u00e7\u00e3o,<\/li>\n<li>Estat\u00edstica, Matem\u00e1tica, Engenharia, Economia ou \u00e1reas relacionadas;<\/li>\n<li>\u00a0Conhecimento b\u00e1sico de programa\u00e7\u00e3o em Python ou R;<\/li>\n<li>\u00a0Familiaridade com bibliotecas de an\u00e1lise de dados como Pandas, NumPy, ou dplyr;<\/li>\n<li>\u00a0Conhecimento b\u00e1sico de SQL para consultas de banco de dados;<\/li>\n<li>Entendimento de conceitos estat\u00edsticos b\u00e1sicos;<\/li>\n<li>\u00a0Experi\u00eancia com ferramentas de visualiza\u00e7\u00e3o de dados como Matplotlib, Seaborn, Tableau, ou Power BI;<\/li>\n<li>\u00a0Habilidade de comunica\u00e7\u00e3o clara e concisa;<\/li>\n<li>\u00a0Capacidade de trabalhar em equipe e colaborar em projetos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u00a0Auxiliar na coleta, limpeza e an\u00e1lise de dados;<\/li>\n<li>\u00a0Participar do desenvolvimento e implementa\u00e7\u00e3o de modelos de machine learning;<\/li>\n<li>\u00a0Criar visualiza\u00e7\u00f5es de dados para comunicar insights;<\/li>\n<li>\u00a0Colaborar com a equipe em projetos de ci\u00eancia de dados.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>29 hora semanais<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Remunera\u00e7\u00e3o:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Bolsa est\u00e1gio + Auxilio transporte;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Observa\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u00a0Trabalhar em projetos junto a google na sede da google for startups;<\/li>\n<li>\u00a0Conhecimento de ferramentas de Big Data (Hadoop, Spark);<\/li>\n<li>\u00a0Experi\u00eancia em projetos acad\u00eamicos ou pessoais de an\u00e1lise de dados;\u2013 Certifica\u00e7\u00f5es ou cursos online em ci\u00eancia de dados ou \u00e1reas relacionadas.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Data m\u00e1xima para envio de curr\u00edculos: 30\/09\/2024<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:curriculos@vemprevenir.onmicrosoft.com\">curriculos@vemprevenir.onmicrosoft.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Estar matriculado em curso de gradua\u00e7\u00e3o em Ci\u00eancia da Computa\u00e7\u00e3o, Estat\u00edstica, Matem\u00e1tica, Engenharia, Economia ou \u00e1reas relacionadas; \u00a0Conhecimento b\u00e1sico de programa\u00e7\u00e3o em Python ou [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118,38,51],"tags":[],"class_list":["post-63628","post","type-post","status-publish","format-standard","hentry","category-ensino-superior-incompleto-em-andamento","category-estagio","category-informatica-ti-programador-desenvolvedor-analista-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Estar matriculado em curso de gradua\u00e7\u00e3o em Ci\u00eancia da Computa\u00e7\u00e3o, Estat\u00edstica, Matem\u00e1tica, Engenharia, Economia ou \u00e1reas relacionadas; \u00a0Conhecimento b\u00e1sico de programa\u00e7\u00e3o em Python ou [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasEmpregoSP\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T12:00:25+00:00\" \/>\n<meta name=\"author\" content=\"Vagas Emprego SP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vagas Emprego SP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/\"},\"author\":{\"name\":\"Vagas Emprego SP\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\"},\"headline\":\"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia &#8211; S\u00e3o Paulo \u2013 SP\",\"datePublished\":\"2024-08-19T12:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"articleSection\":[\"ensino superior incompleto\",\"est\u00e1gio\",\"inform\u00e1tica \\\/ TI \\\/ Web\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/\",\"name\":\"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\"},\"datePublished\":\"2024-08-19T12:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/2024\\\/08\\\/19\\\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia &#8211; S\u00e3o Paulo \u2013 SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"name\":\"VagasEmpregoSP\",\"description\":\"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#organization\",\"name\":\"VagasEmpregoSP\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logovsp2015.jpg\",\"width\":323,\"height\":90,\"caption\":\"VagasEmpregoSP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/#\\\/schema\\\/person\\\/456ec40bd3c8bc7506f4a4408e8f46d5\",\"name\":\"Vagas Emprego SP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"Vagas Emprego SP\"},\"url\":\"https:\\\/\\\/www.vagasempregosp.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP","og_description":"Requisitos: Estar matriculado em curso de gradua\u00e7\u00e3o em Ci\u00eancia da Computa\u00e7\u00e3o, Estat\u00edstica, Matem\u00e1tica, Engenharia, Economia ou \u00e1reas relacionadas; \u00a0Conhecimento b\u00e1sico de programa\u00e7\u00e3o em Python ou [...]","og_url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/","og_site_name":"VagasEmpregoSP","article_published_time":"2024-08-19T12:00:25+00:00","author":"Vagas Emprego SP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vagas Emprego SP","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/#article","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/"},"author":{"name":"Vagas Emprego SP","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5"},"headline":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia &#8211; S\u00e3o Paulo \u2013 SP","datePublished":"2024-08-19T12:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/"},"wordCount":235,"publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"articleSection":["ensino superior incompleto","est\u00e1gio","inform\u00e1tica \/ TI \/ Web"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/","url":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/","name":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia - S\u00e3o Paulo \u2013 SP - VagasEmpregoSP","isPartOf":{"@id":"https:\/\/www.vagasempregosp.com.br\/#website"},"datePublished":"2024-08-19T12:00:25+00:00","breadcrumb":{"@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasempregosp.com.br\/index.php\/2024\/08\/19\/estagio-em-ciencia-de-dados-e-tecnologia-sao-paulo-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasempregosp.com.br\/"},{"@type":"ListItem","position":2,"name":"Est\u00e1gio em Ci\u00eancia de Dados e Tecnologia &#8211; S\u00e3o Paulo \u2013 SP"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasempregosp.com.br\/#website","url":"https:\/\/www.vagasempregosp.com.br\/","name":"VagasEmpregoSP","description":"Vagas de Emprego e Est\u00e1gio em S\u00e3o Paulo","publisher":{"@id":"https:\/\/www.vagasempregosp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasempregosp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasempregosp.com.br\/#organization","name":"VagasEmpregoSP","url":"https:\/\/www.vagasempregosp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","contentUrl":"https:\/\/www.vagasempregosp.com.br\/wp-content\/uploads\/2025\/06\/cropped-logovsp2015.jpg","width":323,"height":90,"caption":"VagasEmpregoSP"},"image":{"@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasempregosp.com.br\/#\/schema\/person\/456ec40bd3c8bc7506f4a4408e8f46d5","name":"Vagas Emprego SP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"Vagas Emprego SP"},"url":"https:\/\/www.vagasempregosp.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63628"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63628\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasempregosp.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}